{"id":5093,"date":"2024-02-17T11:00:56","date_gmt":"2024-02-17T17:00:56","guid":{"rendered":"https:\/\/wpsheeteditor.com\/es\/?p=5093"},"modified":"2024-02-18T13:30:36","modified_gmt":"2024-02-18T19:30:36","slug":"easy-digital-downloads-como-editar-descripciones-productos-masivamente","status":"publish","type":"post","link":"https:\/\/wpsheeteditor.com\/es\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\/","title":{"rendered":"Easy Digital Downloads \u2013 Editar Descripciones de Productos Masivamente"},"content":{"rendered":"<p>En este tutorial te mostramos c\u00f3mo editar las descripciones de tus productos Easy Digital Downloads.<\/p>\n<p>La forma en que describamos nuestros productos ser\u00e1 en gran medida la forma en que nuestros clientes puedan saber m\u00e1s de que tratan nuestros productos.<\/p>\n<p class=\"responsive-video-wrap clr\">\n<div class=\"rve\" data-content-width=\"1200\"><iframe title=\"Easy Digital Downloads \u2013Editar Descripciones de Productos Masivamente\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/4h8Js4kxPZ8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n<p><!-- Responsive Video Embeds plugin by www.kevinleary.net --><\/p>\n<p>Sin embargo, reconocemos que editar descripciones de miles de productos EDD puede ser tedioso, porque tienes que editar cada una de las descripciones individualmente.<\/p>\n<p>Por eso, queremos mostrarte c\u00f3mo editar las descripciones de forma masiva con el <strong>Editor Masivo de Productos de Easy Digital Downloads.<\/strong><\/p>\n<p>Este plug-in te permite editar las descripciones de todos los productos que contienen una palabra clave en sus t\u00edtulos, todos los fondos de pantalla, por ejemplo. Tambi\u00e9n puede ser muy \u00fatil si quieres asignar una descripci\u00f3n predeterminada a todos tus productos que pertenecen a una categor\u00eda o etiqueta espec\u00edfica.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Instala_el_Editor_Masivo_de_Productos_de_Easy_Digital_Downloads\"><\/span>Instala el Editor Masivo de Productos de Easy Digital Downloads<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"vg-buy-now-wrapper\"><p>Obt\u00e9n el plugin profesional para WordPress aqu\u00ed:<\/p>\r\n<p><a href=\"https:\/\/wpsheeteditor.com\/es\/comprar-plugin\/?extension_id=1028&utm_source=website&utm_medium=blog&utm_campaign=\/es\/wp-json\/wp\/v2\/posts\/5093#buy\" class=\"vg-buy-now-shortcode\" target=\"_blank\">Descargar el Editor Masivo de Easy Digital Downloads &#8211; WP Sheet Editor<\/a> - o -\u00a0<a href=\"https:\/\/wpsheeteditor.com\/es\/extensions\/editor-masivo-productos-easy-digital-downloads\/?utm_source=website&utm_medium=blog&utm_campaign=\/es\/wp-json\/wp\/v2\/posts\/5093\" target=\"_blank\" rel=\"noopener\">Conocer m\u00e1s sobre el plugin<\/a><\/p><\/div>\t\t<style>\r\n\r\n\t\t\t.vg-buy-now-wrapper {\r\n\t\t\t\tmargin: 1.5em auto;\r\n\t\t\t\tmax-width: 700px;\r\n\t\t\t\tborder: 1px solid #ddd;\r\n\t\t\t\tborder-left: 0;\r\n\t\t\t\tborder-right: 0;\r\n\t\t\t\tcolor: #000\r\n\t\t\t}\r\n\r\n\t\t\t.vg-buy-now-wrapper .vg-buy-now-shortcode {\r\n\t\t\t\tcolor: #fff !important;\r\n\t\t\t\tpadding: 10px;\r\n\t\t\t\tfont-family: \"Roboto\",Sans-serif;\r\n\t\t\t\ttext-transform: uppercase;\r\n\t\t\t\tbackground-color: #1769c5;\r\n\t\t\t\tborder-radius: 8px;\r\n\t\t\t\tclear: both;\r\n\t\t\t\tdisplay: inline-block\r\n\t\t\t}\r\n\r\n\t\t\t.vg-buy-now-wrapper .vg-buy-now-shortcode:hover {\r\n\t\t\t\topacity: .9\r\n\t\t\t}\t\r\n\t\t<\/style>\r\n\t\t\n<p>Una vez instalado y activado el plugin, ve a <strong>WP Sheet Editor\u00a0&gt; Editar descargas EDD<\/strong> para abrirlo.<\/p>\n<p>Ver\u00e1s una hoja de c\u00e1lculo que contiene todas tus descargas y su informaci\u00f3n completa.<\/p>\n<p><a href=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/04094150\/Hoja-de-EDD.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-15028 size-full\" src=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/04094150\/Hoja-de-EDD.png\" alt=\"editar descripciones de productos edd\" width=\"1912\" height=\"933\" srcset=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/04094150\/Hoja-de-EDD.png 1912w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/04094150\/Hoja-de-EDD-300x146.png 300w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/04094150\/Hoja-de-EDD-1024x500.png 1024w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/04094150\/Hoja-de-EDD-768x375.png 768w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/04094150\/Hoja-de-EDD-1536x750.png 1536w\" sizes=\"(max-width: 1912px) 100vw, 1912px\" \/><\/a><\/p>\n<p>Ahora tendr\u00e1s estas dos opciones:<\/p>\n<h2><span class=\"ez-toc-section\" id=\"1-_Como_editar_descripciones_de_productos_EDD_individualmente\"><\/span><b>1- C\u00f3mo editar descripciones de productos EDD individualmente<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Para editar las descripciones de los productos individualmente en la hoja de c\u00e1lculo, solo tienes que ir a la columna <b>Descripci\u00f3n <\/b>y editar los precios de todos los productos que desees.<\/p>\n<p>Despu\u00e9s de eso, haz clic en <b>Guardar<\/b>.<\/p>\n<p><b>Importante:<\/b> Aunque es una edici\u00f3n individual, te llevar\u00e1 mucho menos tiempo que cuando editas las descripciones de tus productos en el editor de productos Easy Digital Downloads.<\/p>\n<p><a href=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05162118\/Editar-descripciones-de-productos.png\"><img decoding=\"async\" class=\"size-full wp-image-15122 aligncenter\" src=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05162118\/Editar-descripciones-de-productos.png\" alt=\"\" width=\"1907\" height=\"933\" srcset=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05162118\/Editar-descripciones-de-productos.png 1907w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05162118\/Editar-descripciones-de-productos-300x147.png 300w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05162118\/Editar-descripciones-de-productos-1024x501.png 1024w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05162118\/Editar-descripciones-de-productos-768x376.png 768w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05162118\/Editar-descripciones-de-productos-1536x751.png 1536w\" sizes=\"(max-width: 1907px) 100vw, 1907px\" \/><\/a><\/p>\n<h2><span class=\"ez-toc-section\" id=\"2-_Buscar_y_editar_descripciones_de_productos_EDD_por_palabra_clave\"><\/span><b>2- Buscar y editar descripciones de productos EDD por palabra clave<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>El primer paso que hay que dar para encontrar los productos que contienen una palabra clave en el t\u00edtulo es abrir la herramienta <strong>Buscar.<\/strong><\/p>\n<p>Esta herramienta te permite hacer diferentes tipos de b\u00fasquedas avanzadas.<\/p>\n<p><a href=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2022\/10\/05102153\/buscar.productos.png\"><br \/>\n<img decoding=\"async\" class=\"aligncenter wp-image-15101 size-full\" src=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2022\/10\/05102153\/buscar.productos.png\" alt=\"editar descripciones de productos edd\" width=\"1901\" height=\"934\" srcset=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2022\/10\/05102153\/buscar.productos.png 1901w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2022\/10\/05102153\/buscar.productos-300x147.png 300w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2022\/10\/05102153\/buscar.productos-1024x503.png 1024w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2022\/10\/05102153\/buscar.productos-768x377.png 768w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2022\/10\/05102153\/buscar.productos-1536x755.png 1536w\" sizes=\"(max-width: 1901px) 100vw, 1901px\" \/><\/a><\/p>\n<p dir=\"ltr\">Encontrar\u00e1s varios campos diferentes que puedes utilizar para hacer tu b\u00fasqueda m\u00e1s espec\u00edfica:<\/p>\n<ul>\n<li><b>Contiene palabra clave:<\/b> Usa este campo si vas a buscar todas las descargas que contengan una palabra clave espec\u00edfica en el t\u00edtulo.<\/li>\n<li><b>Autor:<\/b>\u00a0Busca tus descargas usando el nombre del usuario que las creo.<\/li>\n<li><b>Categor\u00eda o Etiqueta: <\/b>Filtra tus descargas por categor\u00eda o etiqueta<b>.<\/b><\/li>\n<li><b>Habilitar filtros avanzados:<\/b>\u00a0Esta casilla de verificaci\u00f3n abre filtros avanzados para buscar tus descargas.<\/li>\n<\/ul>\n<p>Para filtrar los productos que contienen una palabra clave en el t\u00edtulo, debes agregar la palabra en el campo:<strong> Contiene palabra clave.<\/strong><\/p>\n<p><a href=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05193858\/buscar-productos-por-palabra-clave-1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15125 size-full\" src=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05193858\/buscar-productos-por-palabra-clave-1.png\" alt=\"editar descripciones de productos descargables\" width=\"1811\" height=\"885\" srcset=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05193858\/buscar-productos-por-palabra-clave-1.png 1811w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05193858\/buscar-productos-por-palabra-clave-1-300x147.png 300w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05193858\/buscar-productos-por-palabra-clave-1-1024x500.png 1024w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05193858\/buscar-productos-por-palabra-clave-1-768x375.png 768w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05193858\/buscar-productos-por-palabra-clave-1-1536x751.png 1536w\" sizes=\"(max-width: 1811px) 100vw, 1811px\" \/><\/a><\/p>\n<p>Cuando se ejecuta la b\u00fasqueda, la hoja de c\u00e1lculo se recarga y te muestra los resultados de la b\u00fasqueda.<\/p>\n<p>En este caso todos los productos que buscamos por palabra clave.<\/p>\n<p><a href=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05194626\/productos-descargables-2.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15126 aligncenter\" src=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05194626\/productos-descargables-2.png\" alt=\"\" width=\"1902\" height=\"926\" srcset=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05194626\/productos-descargables-2.png 1902w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05194626\/productos-descargables-2-300x146.png 300w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05194626\/productos-descargables-2-1024x499.png 1024w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05194626\/productos-descargables-2-768x374.png 768w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05194626\/productos-descargables-2-1536x748.png 1536w\" sizes=\"(max-width: 1902px) 100vw, 1902px\" \/><\/a><\/p>\n<h2><span class=\"ez-toc-section\" id=\"3-_Editar_descripciones_de_los_productos_masivamente\"><\/span>3- <b>Editar descripciones de los productos masivamente<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Para poder editar las descripciones masivamente de los productos filtrados, usaremos el <strong>Editor Masivo<\/strong>.<\/p>\n<p>Esta herramienta te permite hacer diferentes cambios masivos en unos minutos.<\/p>\n<p><a href=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05195037\/editar-descripciones-masivamente.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15127 aligncenter\" src=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05195037\/editar-descripciones-masivamente.png\" alt=\"\" width=\"1902\" height=\"927\" srcset=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05195037\/editar-descripciones-masivamente.png 1902w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05195037\/editar-descripciones-masivamente-300x146.png 300w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05195037\/editar-descripciones-masivamente-1024x499.png 1024w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05195037\/editar-descripciones-masivamente-768x374.png 768w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05195037\/editar-descripciones-masivamente-1536x749.png 1536w\" sizes=\"(max-width: 1902px) 100vw, 1902px\" \/><\/a><\/p>\n<p>Ahora debes selecciones los siguientes valores para establecer una nueva descripci\u00f3n a los productos filtrados:<\/p>\n<ul>\n<li><b>Selecciona las filas que quieres editar:<\/b> Editar todas las filas de mi b\u00fasqueda actual (incluyendo las filas no visibles)<\/li>\n<li><b>\u00bfQu\u00e9 campo quieres editar?:<\/b> Descripci\u00f3n<\/li>\n<li><b>Selecciona el tipo de edici\u00f3n:<\/b> Establecer valor<\/li>\n<li><b>Reemplazar el valor existente por este valor:<\/b> Ingresa la nueva descripci\u00f3n<\/li>\n<li>Haz clic en <b>Ejecutar ahora<\/b><\/li>\n<\/ul>\n<p><a href=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05200226\/editar-descripciones-masivamente-edd.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15128 size-full\" src=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05200226\/editar-descripciones-masivamente-edd.png\" alt=\"editar descripciones de productos edd masivamente\" width=\"1767\" height=\"868\" srcset=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05200226\/editar-descripciones-masivamente-edd.png 1767w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05200226\/editar-descripciones-masivamente-edd-300x147.png 300w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05200226\/editar-descripciones-masivamente-edd-1024x503.png 1024w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05200226\/editar-descripciones-masivamente-edd-768x377.png 768w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05200226\/editar-descripciones-masivamente-edd-1536x755.png 1536w\" sizes=\"(max-width: 1767px) 100vw, 1767px\" \/><\/a><\/p>\n<p>Despu\u00e9s de eso, las descripciones de tus productos ser\u00e1n agregadas.<\/p>\n<p><a href=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05201748\/editar-descripciones-masivamente-de-productos-edd.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15129 aligncenter\" src=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05201748\/editar-descripciones-masivamente-de-productos-edd.png\" alt=\"\" width=\"1919\" height=\"935\" srcset=\"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05201748\/editar-descripciones-masivamente-de-productos-edd.png 1919w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05201748\/editar-descripciones-masivamente-de-productos-edd-300x146.png 300w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05201748\/editar-descripciones-masivamente-de-productos-edd-1024x499.png 1024w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05201748\/editar-descripciones-masivamente-de-productos-edd-768x374.png 768w, https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/05201748\/editar-descripciones-masivamente-de-productos-edd-1536x748.png 1536w\" sizes=\"(max-width: 1919px) 100vw, 1919px\" \/><\/a><\/p>\n<p>Como puedes ver, las dos opciones que te presentamos te ayudan a ahorrar muchas horas de trabajo, porque no tienes que abrir muchas pesta\u00f1as.<\/p>\n<p>Puedes agregar r\u00e1pidamente descripciones de productos EDD individuales en la hoja de c\u00e1lculo sin tener que abrirlos uno por uno. Adem\u00e1s, puedes establecer una descripci\u00f3n para todos los productos que selecciones.<\/p>\n<p>Para m\u00e1s tutoriales <a href=\"https:\/\/wpsheeteditor.com\/es\/blog\/\">visita nuestro blog<\/a>.<\/p>\n<div class=\"vg-buy-now-wrapper\"><p>Obt\u00e9n el plugin profesional para WordPress aqu\u00ed:<\/p>\r\n<p><a href=\"https:\/\/wpsheeteditor.com\/es\/comprar-plugin\/?extension_id=1028&utm_source=website&utm_medium=blog&utm_campaign=\/es\/wp-json\/wp\/v2\/posts\/5093#buy\" class=\"vg-buy-now-shortcode\" target=\"_blank\">Descargar el Editor Masivo de Easy Digital Downloads &#8211; WP Sheet Editor<\/a> - o -\u00a0<a href=\"https:\/\/wpsheeteditor.com\/es\/extensions\/editor-masivo-productos-easy-digital-downloads\/?utm_source=website&utm_medium=blog&utm_campaign=\/es\/wp-json\/wp\/v2\/posts\/5093\" target=\"_blank\" rel=\"noopener\">Conocer m\u00e1s sobre el plugin<\/a><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En este tutorial te mostramos c\u00f3mo editar las descripciones de tus productos Easy Digital Downloads. La forma en que describamos nuestros productos ser\u00e1 en gran medida la forma en que nuestros clientes puedan saber m\u00e1s de que tratan nuestros productos. Sin embargo, reconocemos que editar descripciones de miles de productos EDD puede ser tedioso, porque [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_custom_body_class":"","_custom_post_class":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"feature":[78],"plugin":[18],"class_list":["post-5093","post","type-post","status-publish","format-standard","hentry","category-guias","feature-editor-masivo","plugin-editor-masivo-productos-easy-digital-downloads","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Easy Digital Downloads \u2013 Editar Descripciones de Productos Masivamente<\/title>\n<meta name=\"description\" content=\"Descubre c\u00f3mo editar descripciones de productos de tu tienda Easy Digital Downloads. Lo har\u00e1s usando en una hoja de c\u00e1lculo de productos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wpsheeteditor.com\/es\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Easy Digital Downloads \u2013 Editar Descripciones de Productos Masivamente\" \/>\n<meta property=\"og:description\" content=\"Descubre c\u00f3mo editar descripciones de productos de tu tienda Easy Digital Downloads. Lo har\u00e1s usando en una hoja de c\u00e1lculo de productos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wpsheeteditor.com\/es\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\/\" \/>\n<meta property=\"og:site_name\" content=\"WP Sheet Editor en Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-17T17:00:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-18T19:30:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wpsheeteditor.com\/es\/wp-content\/uploads\/sites\/3\/2019\/07\/Hoja-de-EDD.png\" \/>\n<meta name=\"author\" content=\"Diego Portillo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diego Portillo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\\\/\"},\"author\":{\"name\":\"Diego Portillo\",\"@id\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/#\\\/schema\\\/person\\\/2fa7b5e4dcba429eade500d44d548dc6\"},\"headline\":\"Easy Digital Downloads \u2013 Editar Descripciones de Productos Masivamente\",\"datePublished\":\"2024-02-17T17:00:56+00:00\",\"dateModified\":\"2024-02-18T19:30:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\\\/\"},\"wordCount\":658,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2019\\\/07\\\/Hoja-de-EDD.png\",\"articleSection\":[\"Gu\u00edas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\\\/\",\"url\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\\\/\",\"name\":\"Easy Digital Downloads \u2013 Editar Descripciones de Productos Masivamente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2019\\\/07\\\/Hoja-de-EDD.png\",\"datePublished\":\"2024-02-17T17:00:56+00:00\",\"dateModified\":\"2024-02-18T19:30:36+00:00\",\"description\":\"Descubre c\u00f3mo editar descripciones de productos de tu tienda Easy Digital Downloads. Lo har\u00e1s usando en una hoja de c\u00e1lculo de productos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.wpsheeteditor.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2019\\\/07\\\/04094150\\\/Hoja-de-EDD.png\",\"contentUrl\":\"https:\\\/\\\/media.wpsheeteditor.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2019\\\/07\\\/04094150\\\/Hoja-de-EDD.png\",\"width\":1912,\"height\":933},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Easy Digital Downloads \u2013 Editar Descripciones de Productos Masivamente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/\",\"name\":\"WP Sheet Editor en Espa\u00f1ol\",\"description\":\"Edita miles de posts y p\u00e1ginas r\u00e1pidamente\",\"publisher\":{\"@id\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/#organization\",\"name\":\"WP Sheet Editor\",\"url\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.wpsheeteditor.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/06\\\/26203459\\\/logo-248x102.png\",\"contentUrl\":\"https:\\\/\\\/media.wpsheeteditor.com\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/06\\\/26203459\\\/logo-248x102.png\",\"width\":248,\"height\":102,\"caption\":\"WP Sheet Editor\"},\"image\":{\"@id\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wpsheeteditor.com\\\/es\\\/#\\\/schema\\\/person\\\/2fa7b5e4dcba429eade500d44d548dc6\",\"name\":\"Diego Portillo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbfa7c6341d4b7068d4ae6787145c8470d8876dc2b33aa3b840dd72fcca64d45?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbfa7c6341d4b7068d4ae6787145c8470d8876dc2b33aa3b840dd72fcca64d45?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fbfa7c6341d4b7068d4ae6787145c8470d8876dc2b33aa3b840dd72fcca64d45?s=96&d=mm&r=g\",\"caption\":\"Diego Portillo\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Easy Digital Downloads \u2013 Editar Descripciones de Productos Masivamente","description":"Descubre c\u00f3mo editar descripciones de productos de tu tienda Easy Digital Downloads. Lo har\u00e1s usando en una hoja de c\u00e1lculo de productos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wpsheeteditor.com\/es\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\/","og_locale":"es_ES","og_type":"article","og_title":"Easy Digital Downloads \u2013 Editar Descripciones de Productos Masivamente","og_description":"Descubre c\u00f3mo editar descripciones de productos de tu tienda Easy Digital Downloads. Lo har\u00e1s usando en una hoja de c\u00e1lculo de productos.","og_url":"https:\/\/wpsheeteditor.com\/es\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\/","og_site_name":"WP Sheet Editor en Espa\u00f1ol","article_published_time":"2024-02-17T17:00:56+00:00","article_modified_time":"2024-02-18T19:30:36+00:00","og_image":[{"url":"https:\/\/wpsheeteditor.com\/es\/wp-content\/uploads\/sites\/3\/2019\/07\/Hoja-de-EDD.png","type":"","width":"","height":""}],"author":"Diego Portillo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Diego Portillo","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wpsheeteditor.com\/es\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\/#article","isPartOf":{"@id":"https:\/\/wpsheeteditor.com\/es\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\/"},"author":{"name":"Diego Portillo","@id":"https:\/\/wpsheeteditor.com\/es\/#\/schema\/person\/2fa7b5e4dcba429eade500d44d548dc6"},"headline":"Easy Digital Downloads \u2013 Editar Descripciones de Productos Masivamente","datePublished":"2024-02-17T17:00:56+00:00","dateModified":"2024-02-18T19:30:36+00:00","mainEntityOfPage":{"@id":"https:\/\/wpsheeteditor.com\/es\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\/"},"wordCount":658,"commentCount":0,"publisher":{"@id":"https:\/\/wpsheeteditor.com\/es\/#organization"},"image":{"@id":"https:\/\/wpsheeteditor.com\/es\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\/#primaryimage"},"thumbnailUrl":"https:\/\/wpsheeteditor.com\/es\/wp-content\/uploads\/sites\/3\/2019\/07\/Hoja-de-EDD.png","articleSection":["Gu\u00edas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wpsheeteditor.com\/es\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wpsheeteditor.com\/es\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\/","url":"https:\/\/wpsheeteditor.com\/es\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\/","name":"Easy Digital Downloads \u2013 Editar Descripciones de Productos Masivamente","isPartOf":{"@id":"https:\/\/wpsheeteditor.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wpsheeteditor.com\/es\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\/#primaryimage"},"image":{"@id":"https:\/\/wpsheeteditor.com\/es\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\/#primaryimage"},"thumbnailUrl":"https:\/\/wpsheeteditor.com\/es\/wp-content\/uploads\/sites\/3\/2019\/07\/Hoja-de-EDD.png","datePublished":"2024-02-17T17:00:56+00:00","dateModified":"2024-02-18T19:30:36+00:00","description":"Descubre c\u00f3mo editar descripciones de productos de tu tienda Easy Digital Downloads. Lo har\u00e1s usando en una hoja de c\u00e1lculo de productos.","breadcrumb":{"@id":"https:\/\/wpsheeteditor.com\/es\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wpsheeteditor.com\/es\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wpsheeteditor.com\/es\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\/#primaryimage","url":"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/04094150\/Hoja-de-EDD.png","contentUrl":"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2019\/07\/04094150\/Hoja-de-EDD.png","width":1912,"height":933},{"@type":"BreadcrumbList","@id":"https:\/\/wpsheeteditor.com\/es\/easy-digital-downloads-como-editar-descripciones-productos-masivamente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wpsheeteditor.com\/es\/"},{"@type":"ListItem","position":2,"name":"Easy Digital Downloads \u2013 Editar Descripciones de Productos Masivamente"}]},{"@type":"WebSite","@id":"https:\/\/wpsheeteditor.com\/es\/#website","url":"https:\/\/wpsheeteditor.com\/es\/","name":"WP Sheet Editor en Espa\u00f1ol","description":"Edita miles de posts y p\u00e1ginas r\u00e1pidamente","publisher":{"@id":"https:\/\/wpsheeteditor.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wpsheeteditor.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wpsheeteditor.com\/es\/#organization","name":"WP Sheet Editor","url":"https:\/\/wpsheeteditor.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wpsheeteditor.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2016\/06\/26203459\/logo-248x102.png","contentUrl":"https:\/\/media.wpsheeteditor.com\/wp-content\/uploads\/sites\/3\/2016\/06\/26203459\/logo-248x102.png","width":248,"height":102,"caption":"WP Sheet Editor"},"image":{"@id":"https:\/\/wpsheeteditor.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/wpsheeteditor.com\/es\/#\/schema\/person\/2fa7b5e4dcba429eade500d44d548dc6","name":"Diego Portillo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fbfa7c6341d4b7068d4ae6787145c8470d8876dc2b33aa3b840dd72fcca64d45?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fbfa7c6341d4b7068d4ae6787145c8470d8876dc2b33aa3b840dd72fcca64d45?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fbfa7c6341d4b7068d4ae6787145c8470d8876dc2b33aa3b840dd72fcca64d45?s=96&d=mm&r=g","caption":"Diego Portillo"}}]}},"_links":{"self":[{"href":"https:\/\/wpsheeteditor.com\/es\/wp-json\/wp\/v2\/posts\/5093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wpsheeteditor.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wpsheeteditor.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wpsheeteditor.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wpsheeteditor.com\/es\/wp-json\/wp\/v2\/comments?post=5093"}],"version-history":[{"count":3,"href":"https:\/\/wpsheeteditor.com\/es\/wp-json\/wp\/v2\/posts\/5093\/revisions"}],"predecessor-version":[{"id":22621,"href":"https:\/\/wpsheeteditor.com\/es\/wp-json\/wp\/v2\/posts\/5093\/revisions\/22621"}],"wp:attachment":[{"href":"https:\/\/wpsheeteditor.com\/es\/wp-json\/wp\/v2\/media?parent=5093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wpsheeteditor.com\/es\/wp-json\/wp\/v2\/categories?post=5093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wpsheeteditor.com\/es\/wp-json\/wp\/v2\/tags?post=5093"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/wpsheeteditor.com\/es\/wp-json\/wp\/v2\/feature?post=5093"},{"taxonomy":"plugin","embeddable":true,"href":"https:\/\/wpsheeteditor.com\/es\/wp-json\/wp\/v2\/plugin?post=5093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}